{"id":360,"date":"2024-03-23T08:34:54","date_gmt":"2024-03-23T12:34:54","guid":{"rendered":"https:\/\/bethawaiisports.com\/?page_id=360"},"modified":"2024-03-29T22:36:39","modified_gmt":"2024-03-30T02:36:39","slug":"schedule","status":"publish","type":"page","link":"https:\/\/bethawaiisports.com\/index.php\/schedule\/","title":{"rendered":"Schedule, Scores, &#038; Odds"},"content":{"rendered":"\n<div id=\"schedule-iframe-container\"><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/bethawaiisports.com\/index.php\/wp-json\/wp\/v2\/pages\/360"}],"collection":[{"href":"https:\/\/bethawaiisports.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bethawaiisports.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bethawaiisports.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bethawaiisports.com\/index.php\/wp-json\/wp\/v2\/comments?post=360"}],"version-history":[{"count":3,"href":"https:\/\/bethawaiisports.com\/index.php\/wp-json\/wp\/v2\/pages\/360\/revisions"}],"predecessor-version":[{"id":487,"href":"https:\/\/bethawaiisports.com\/index.php\/wp-json\/wp\/v2\/pages\/360\/revisions\/487"}],"wp:attachment":[{"href":"https:\/\/bethawaiisports.com\/index.php\/wp-json\/wp\/v2\/media?parent=360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}